{"id":21145,"date":"2012-12-14T21:56:20","date_gmt":"2012-12-14T21:56:20","guid":{"rendered":"https:\/\/wordpress.org\/plugins-wp\/flodjishare\/"},"modified":"2019-01-28T19:55:40","modified_gmt":"2019-01-28T19:55:40","slug":"flodjishare","status":"publish","type":"plugin","link":"https:\/\/lmo.wordpress.org\/plugins\/flodjishare\/","author":11041391,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"5.2","stable_tag":"trunk","tested":"5.0.25","requires":"5.0","requires_php":"","requires_plugins":"","header_name":"flodjiShare","header_author":"flodji","header_description":"","assets_banners_color":"","last_updated":"2019-01-28 19:55:40","external_support_url":"","external_repository_url":"","donate_link":"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&hosted_button_id=K9U25CKQNA5GL","header_plugin_uri":"http:\/\/flodji.de\/downloads\/flodjishare-fuer-wordpress\/","header_author_uri":"https:\/\/flodji.de","rating":5,"author_block_rating":0,"active_installs":20,"downloads":5672,"num_ratings":2,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation","faq","changelog"],"tags":[],"upgrade_notice":{"":"<p>Version 5.2:<\/p>\n\n<ul>\n<li>Fehlerbehebung: Der Pinterest Share Button lies sich im alten Design ohne Counter nicht aktivieren.<\/li>\n<li>Optimierung: Die Sharebar &uuml;berdeckt den Footer nicht, wenn ganz nach unten gescrollt wird.<\/li>\n<\/ul>\n\n<p>Version 5.1:<\/p>\n\n<ul>\n<li>Fehlerbehebung: Das Deaktivieren der Share Buttons funktionierte nicht &uuml;berall<\/li>\n<\/ul>\n\n<p>Version 5.0:<\/p>\n\n<ul>\n<li>Umstellung des Klickz&auml;hlers auf Metadaten<\/li>\n<li>Durch die Umstellung werden die in der Datenbank gespeicherten Klicks auf die Share Buttons leider nicht mehr angezeigt. Sie sind aber weiterhin in der Datenbank vorhanden.<\/li>\n<li>Wordpress 5.x Kompatibel<\/li>\n<li>Opengraph Support, Rich Snippets, Twitter Cards, Meta Keywords und andere SEO Funktionen entfernt. Diese werden mittlerweile durch Themes oder SEO Plugins erzeugt und werden somit nicht mehr ben&ouml;tigt.<\/li>\n<li>Einstellungen angepasst und &uuml;berarbeitet<\/li>\n<li>Erweiterung des Datenschutzhinweises (Tooltip oder Link zur Datenschutzseite)<\/li>\n<li>Nicht genutzte \/ nicht mehr zeitgem&auml;&szlig;e Funktionen entfernt<\/li>\n<\/ul>\n\n<p>Version 4.1:<\/p>\n\n<ul>\n<li>flodjiShare ist auch Wordpress 4.3 kompatibel<\/li>\n<\/ul>\n\n<p>Version 4.0:<\/p>\n\n<ul>\n<li>Code optimiert: CSS Anweisungen f&uuml;r die mobile Share Bar angepasst, so dass keine Rahmen mehr um die Share Buttons erscheinen k&ouml;nnen.<\/li>\n<\/ul>\n\n<p>Version 3.9.9:<\/p>\n\n<ul>\n<li>Code optimiert: CSS Anweisungen angepasst, so dass keine Rahmen mehr um die Buttons im Flatmix entstehen k&ouml;nnen.<\/li>\n<li>Neue Option: Gr&ouml;&szlig;e der Counterbox im Flatmix Design kann nun ge&auml;ndert werden.<\/li>\n<li>Backend: Links im Backend aufger&auml;umt.<\/li>\n<li>Bilder: found-footage.de Logo aktualisiert.<\/li>\n<li>Neue Funktion: Der Speichern Button in den flodjiShare Einstellungen befindet sich nun sowohl &uuml;ber als auch unter den Einstellungen.<\/li>\n<\/ul>\n\n<p>Version 3.9.8:<\/p>\n\n<ul>\n<li>Code optimiert: Bessere Kompatibilit&auml;t zu Wordpress Installationen in Unterordnern.<\/li>\n<li>Neue Funktion: Seitenaufrufe werden auf Wunsch nun auch in der Beitrags- \/ Seiten&uuml;bersicht angezeigt.<\/li>\n<li>Code optimiert: Inline CSS Strukturen in css Datei ausgelagert.<\/li>\n<\/ul>\n\n<p>Version 3.9.7:<\/p>\n\n<ul>\n<li>Code optimiert: site_url anstatt home_url verwendet um Fehler bei WP Installationen in Unterordnern zu vermeiden.<\/li>\n<li>Neue Funktion: Beitrags Statistiken unter den Share Buttons. Hier werden alle Shares zusammengerechnet und die Anzahl der Seitenaufrufe angezeigt.<\/li>\n<\/ul>\n\n<p>Version 3.9.6:<\/p>\n\n<ul>\n<li>Fehler behoben: Problem mit Sonderzeichen beim Teilen &uuml;ber Whatsapp behoben.<\/li>\n<\/ul>\n\n<p>Version 3.9.5:<\/p>\n\n<ul>\n<li>Fehler behoben: Bei aktiviertem Wordpress SEO Plugin wurde die falsche Description in die Metatags eingef&uuml;gt.<\/li>\n<\/ul>\n\n<p>Version 3.9.4:<\/p>\n\n<ul>\n<li>Fehler behoben: flattr und Digg Button fehlten im Flatmix Design<\/li>\n<li>Fehler behoben: Bei manchen Themes trat im Flatmix Design ein unsch&ouml;ner Abstand zwischen Logo und Counter auf<\/li>\n<li>Fehler behoben: Buttons im Flatmix Design konnten nicht zentriert werden<\/li>\n<\/ul>\n\n<p>Version 3.9.3:<\/p>\n\n<ul>\n<li>Fehler behoben: Problem mit Umlauten im Klickz&auml;hler behoben. Umlaute werden nun f&uuml;r den Z&auml;hlvorgang umgewandelt.<\/li>\n<li>Fehler behoben: Problem f&uuml;r Fehlermeldung: Warning: stripslashes() expects parameter 1 to be string, array given .... behoben.<\/li>\n<li>Code Optimierungen: Jeder Share Button wird jetzt &uuml;ber eine eigene Funktion aufgerufen.<\/li>\n<li>Button Mix: Bei aktiviertem Flat Design kann nun ein Mix aus Bild und CSS Button aktiviert werden (nur bei aktiviertem Counter)<\/li>\n<\/ul>\n\n<p>Version 3.9.2:<\/p>\n\n<ul>\n<li>Neue Funktion: Die &Uuml;berschrift der Share Buttons (z.B. Diesen Beitrag teilen) kann nun in der Gr&ouml;&szlig;e angepasst werden.<\/li>\n<li>Neue Funktion: Found-Footage.de Feed Widget eingebaut.<\/li>\n<li>Neue Funktion: Datenbank Pr&auml;fix kann nun ge&auml;ndert werden.<\/li>\n<\/ul>\n\n<p>Version 3.9.1:<\/p>\n\n<ul>\n<li>Bugfix: Problem mit Klickz&auml;hler und Umlauten behoben.<\/li>\n<\/ul>\n\n<p>Version 3.9:<\/p>\n\n<ul>\n<li>Bugfix: CSS Klassen wurden nicht geladen, wenn der Klickz&auml;hler deaktiviert war.<\/li>\n<\/ul>\n\n<p>Version 3.8.1:<\/p>\n\n<ul>\n<li>Fehler behoben: CSS Fehler beim Flat Design behoben<\/li>\n<\/ul>\n\n<p>Version 3.8:<\/p>\n\n<ul>\n<li>Neues Design: Flat Design<\/li>\n<li>Neue Funktion: Gro&szlig;e Buttons aktivieren (Button Design)<\/li>\n<li>Neue Funktion: Buttons zentrieren (Alle Designs)<\/li>\n<\/ul>\n\n<p>Version 3.7:<\/p>\n\n<ul>\n<li>Klick Counter: Problem mit Umlauten im Title behoben.<\/li>\n<\/ul>\n\n<p>Version 3.6:<\/p>\n\n<ul>\n<li>Klick Counter: Weitere Filter f&uuml;r den Klickz&auml;hler.<\/li>\n<\/ul>\n\n<p>Version 3.5:<\/p>\n\n<ul>\n<li>Klick Counter: Es kann nun nach einzelnen Netzwerken gefiltert werden.<\/li>\n<li>Neue Buttons: Add to Feedly + Pocket Buttons hinzugef&uuml;gt.<\/li>\n<li>Fehlender Button: Amazon Button (Plugin Einstellungen) fehlte.<\/li>\n<li>Whatsapp Share Button: Der Button ist jetzt auch f&uuml;r Android User mit aktueller Whatsapp Version nutzbar.<\/li>\n<\/ul>\n\n<p>Version 3.4:<\/p>\n\n<ul>\n<li>Code aufger&auml;mt: Veraltete PHP Funktionen ersetzt.<\/li>\n<li>Einstellungen angepasst: Rechte Spalte erneuert und Klickz&auml;hler &uuml;berarbeitet.<\/li>\n<li>Buttons: GIF Buttons in PNG Dateien umgewandelt und komprimiert<\/li>\n<\/ul>\n\n<p>Version 3.3:<\/p>\n\n<ul>\n<li>Neue Funktion: Sharebar f&uuml;r Android und iOS Ger&auml;te<\/li>\n<\/ul>\n\n<p>Version 3.2:<\/p>\n\n<ul>\n<li>Neuer Button: Whatsapp Share Button hinzugef&uuml;gt (Aktuell nur f&uuml;r iOS Ger&auml;te).<\/li>\n<\/ul>\n\n<p>Version 3.1:<\/p>\n\n<ul>\n<li>Korrektur: Feed Adresse in den Einstellungen korrigiert.<\/li>\n<\/ul>\n\n<p>Version 3.0:<\/p>\n\n<ul>\n<li>Neue Funktion: Bis zu drei eigene Share Buttons definierbar.<\/li>\n<li>Neue Funktion: Google News Keywords Tag<\/li>\n<li>Neue Funktion: Keywords Metatag<\/li>\n<\/ul>\n\n<p>Version 2.9:<\/p>\n\n<ul>\n<li>Bugfix: Kleinen CSS Fehler behoben.<\/li>\n<li>Neue Funktion: flodjiShare kann jetzt durch Sprachdateien &uuml;bersetzt werden.<\/li>\n<\/ul>\n\n<p>Version 2.8:<\/p>\n\n<ul>\n<li>Code Update: Kleine Sch&ouml;hnheits OP an den Plugin Einstellungen<\/li>\n<\/ul>\n\n<p>Version 2.7:<\/p>\n\n<ul>\n<li>Code Update: Kleinere Korekturen<\/li>\n<li>Neue Funktion: flodjiShare in Kategorie-Ansicht, Archiven und Suchergebnissen aktivieren \/ deaktivieren<\/li>\n<li>Neue Funktion: Meta Description Tag ein- \/ausblenden<\/li>\n<\/ul>\n\n<p>Version 2.6:<\/p>\n\n<ul>\n<li>Neuer Button: Flattr Button hinzugef&uuml;gt.<\/li>\n<li>Fehler behoben: Der Support Link \/ Datenschutz Hinweis wurde teilweise neben den Share Buttons angezeigt.<\/li>\n<\/ul>\n\n<p>Version 2.5:<\/p>\n\n<ul>\n<li>Neue Funktion: Metabox unter Beitr&auml;gen, Seiten und Custom Post Types f&uuml;r individuelle Snippet Gestaltung.<\/li>\n<li>Neue Funktion: Einzelne Beitr&auml;ge\/Seiten\/Custom Post Types per ID ausschlie&szlig;en.<\/li>\n<\/ul>\n\n<p>Version 2.4:<\/p>\n\n<ul>\n<li>Code Update: Klickz&auml;hler z&auml;hlt nun keine Bots mehr.<\/li>\n<li>Code Update: Bl&auml;tterfunktion f&uuml;r Klickz&auml;hler optimiert.<\/li>\n<\/ul>\n\n<p>Version 2.3:<\/p>\n\n<ul>\n<li>Neue Anzeigeposition: &Uuml;ber und Unter Beitr&auml;ge gleichzeitig.<\/li>\n<li>Google Plus Authorship Markup<\/li>\n<li>Share Buttons f&uuml;r einzelne Custom-Post-Types aktivieren bzw. deaktivieren<\/li>\n<li>Multi-Autor Unterst&uuml;tzung f&uuml;r Google Authorship Markup und Twitter Cards.<\/li>\n<\/ul>\n\n<p>Version 2.2:<\/p>\n\n<ul>\n<li>Fehler behoben: Share Buttons wurden auch im Feed angezeigt.<\/li>\n<\/ul>\n\n<p>Version 2.1:<\/p>\n\n<ul>\n<li>Neue Funktion: Klickz&auml;hler f&uuml;r die Share-Buttons im Metro Design (Kann nach Bedarf aktiviert bzw. deaktiviert werden).<\/li>\n<li>Code Update: Opengraph Schema wird nur noch bei aktiviertem Opengraph Support angezeigt.<\/li>\n<li>Neue Funktion: flodjiShare Einstellungen haben jetzt eigene Men&uuml;punkte im WordPress Admin-Bereich.<\/li>\n<li>Neue Funktion: Neuer Punkt &quot;flodjiShare Klick Counter&quot; im flodjiShare Men&uuml;. Zeigt die Anzahl der Klicks auf die Buttons pro Button bzw. pro Beitrag an.<\/li>\n<li>Code Update: CSS-Anweisungen erfolgen jetzt aus eigener CSS-Datei.<\/li>\n<\/ul>\n\n<p>Version 2.0:<\/p>\n\n<ul>\n<li>Code Update: Neues Meta Tag f&uuml;r Rich Snippets: Interaction Count. In diesem Meta Tag wird die Anzahl der Kommentare f&uuml;r einen Artikel angezeigt.<\/li>\n<li>Code Update: Schema aus HTML Tag entfernt und in Meta Tag Bereich eingef&uuml;gt.<\/li>\n<\/ul>\n\n<p>Version 1.9:<\/p>\n\n<ul>\n<li>Einstellungen &uuml;berarbeitet:\n\n<ul>\n<li>flodji.de Feed und Links hinzugef&uuml;gt<\/li>\n<\/ul><\/li>\n<li>Datenschutzhinweis-Option eingebaut<\/li>\n<li>Deaktivierbaren Supportlink eingebaut<\/li>\n<\/ul>\n\n<p>Version 1.8:<\/p>\n\n<ul>\n<li>Text &uuml;ber den Buttons ist nun editierbar.<\/li>\n<li>Facebook Link in den Plugin Einstellungen korrigiert.<\/li>\n<\/ul>\n\n<p>Version 1.7:<\/p>\n\n<ul>\n<li>Buttons k&ouml;nnen nun auch ganz einfach per Shortcode [flodjishare] eingebunden werden.<\/li>\n<\/ul>\n\n<p>Version 1.6:<\/p>\n\n<ul>\n<li>Metro Design lies sich nicht mehr deaktivieren.<\/li>\n<\/ul>\n\n<p>Version 1.5:<\/p>\n\n<ul>\n<li>Zus&auml;tzliches Design (metro) ausw&auml;hlbar<\/li>\n<li>Kleinere Bugfixes im Code (z.B. Fehler bei fehlendem Excerpt)<\/li>\n<\/ul>\n\n<p>Version 1.4:<\/p>\n\n<ul>\n<li>Neue Share Buttons: LinkedIn, Pinterest, Stumbleupon, Tumblr<\/li>\n<li>Neues Buttonset<\/li>\n<\/ul>"},"ratings":{"1":0,"2":0,"3":0,"4":0,"5":"2"},"assets_icons":[],"assets_banners":[],"assets_blueprints":{},"all_blocks":[],"tagged_versions":[],"block_files":[],"assets_screenshots":{"screenshot-2.png":{"filename":"screenshot-2.png","revision":"2020736","resolution":"2","location":"plugin","width":783,"height":133},"screenshot-1.png":{"filename":"screenshot-1.png","revision":"2020736","resolution":"1","location":"plugin","width":794,"height":155},"screenshot-3.png":{"filename":"screenshot-3.png","revision":"2020736","resolution":"3","location":"plugin","width":773,"height":138}},"screenshots":{"1":"Standard-Buttons im Einsatz","2":"CSS-Design Buttons im Einsatz","3":"Das neue Flat Design"}},"plugin_section":[],"plugin_tags":[157,138,174,159,487],"plugin_category":[],"plugin_contributors":[89364],"plugin_business_model":[],"class_list":["post-21145","plugin","type-plugin","status-publish","hentry","plugin_tags-facebook","plugin_tags-share","plugin_tags-social","plugin_tags-twitter","plugin_tags-xing","plugin_contributors-flodji","plugin_committers-flodji"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/s.w.org\/plugins\/geopattern-icon\/flodjishare.svg","icon_2x":false,"generated":true},"screenshots":[{"src":"https:\/\/ps.w.org\/flodjishare\/trunk\/screenshot-1.png?rev=2020736","caption":"Standard-Buttons im Einsatz"},{"src":"https:\/\/ps.w.org\/flodjishare\/trunk\/screenshot-2.png?rev=2020736","caption":"CSS-Design Buttons im Einsatz"},{"src":"https:\/\/ps.w.org\/flodjishare\/trunk\/screenshot-3.png?rev=2020736","caption":"Das neue Flat Design"}],"raw_content":"<!--section=description-->\n<p>EN:<\/p>\n\n<p>Just install flodjiShare to enable Social Sharing on your Wordpress site.<\/p>\n\n<p>Let Visitors share your Posts, Pages and Custom Post Types on these social networks to increase traffic:<\/p>\n\n<p>Facebook\nTwitter\nDigg\nDelicious\nGoogle Plus\nXing\nLinkedIn\nPinterest\nStumbleupon\nTumblr.\nFlattr\nWhatsapp\nPocket\nFeedly<\/p>\n\n<p>Features:<\/p>\n\n<p>Wordpress SEO Compatibility\nClick Counter\nPost \/ Page Hit Counter\nPost Statistics\nFast Loading\nImage, CSS or Flat Layout\nMobile Sharebar for Android and iOS Devices\nPosition: Below Content, Above Content, Both or shortcode\nTranslation ready!<\/p>\n\n<p>DE:<\/p>\n\n<p>Mit flodjiShare wird Betreibern einer WordPress-Seite eine einfache L&ouml;sung angeboten die Social Sharing und Bookmark Buttons der gro&szlig;en Netzwerke in die eigene Seite einzubinden.<\/p>\n\n<p>Die folgenden Buttons k&ouml;nnen nach belieben aktiviert bzw. deaktiviert werden:<\/p>\n\n<ul>\n<li>Facebook<\/li>\n<li>Twitter<\/li>\n<li>Digg<\/li>\n<li>Delicious<\/li>\n<li>Google Plus<\/li>\n<li>Xing<\/li>\n<li>LinkedIn<\/li>\n<li>Pinterest<\/li>\n<li>Stumbleupon<\/li>\n<li>Tumblr<\/li>\n<li>Flattr<\/li>\n<li>Whatsapp<\/li>\n<li>Pocket<\/li>\n<li>Feedly<\/li>\n<\/ul>\n\n<p>Features:<\/p>\n\n<ul>\n<li>Kompatibel mit Wordpress SEO<\/li>\n<li>Klickz&auml;hler<\/li>\n<li>Seitenaufrufe z&auml;hlen<\/li>\n<li>Beitrags Statistiken unter den Share Buttons<\/li>\n<li>Schnelle Ladezeit<\/li>\n<li>Button, CSS oder Flat Layout<\/li>\n<li>Sharebar f&uuml;r Android und iOS Ger&auml;te<\/li>\n<li>Position: Unten, Oben, Beides oder individuell per Shortcode<\/li>\n<li>Einzelne Beitr&auml;ge\/Seiten\/Custom Post Types per ID ausschlie&szlig;en<\/li>\n<\/ul>\n\n<!--section=installation-->\n<ol>\n<li>Upload the flodjishare Folder to the \/wp-content\/plugins\/ directory<\/li>\n<li>Activate the plugin through the 'Plugins' menu in WordPress<\/li>\n<li>Go to flodjiShare Options and configure the Plugin<\/li>\n<li>Save<\/li>\n<\/ol>\n\n<!--section=faq-->\n<dl>\n<dt>Bis jetzt noch keine Fragen<\/dt>\n<dd><\/dd>\n\n<\/dl>\n\n<!--section=changelog-->\n<p>Version 5.2:<\/p>\n\n<ul>\n<li>Fehlerbehebung: Der Pinterest Share Button lies sich im alten Design ohne Counter nicht aktivieren.<\/li>\n<li>Optimierung: Die Sharebar &uuml;berdeckt den Footer nicht, wenn ganz nach unten gescrollt wird.<\/li>\n<\/ul>\n\n<p>Version 5.1:<\/p>\n\n<ul>\n<li>Fehlerbehebung: Das Deaktivieren der Share Buttons funktionierte nicht &uuml;berall<\/li>\n<\/ul>\n\n<p>Version 5.0:<\/p>\n\n<ul>\n<li>Umstellung des Klickz&auml;hlers auf Metadaten<\/li>\n<li>Durch die Umstellung werden die in der Datenbank gespeicherten Klicks auf die Share Buttons leider nicht mehr angezeigt. Sie sind aber weiterhin in der Datenbank vorhanden.<\/li>\n<li>Wordpress 5.x Kompatibel<\/li>\n<li>Opengraph Support, Rich Snippets, Twitter Cards, Meta Keywords und andere SEO Funktionen entfernt. Diese werden mittlerweile durch Themes oder SEO Plugins erzeugt und werden somit nicht mehr ben&ouml;tigt.<\/li>\n<li>Einstellungen angepasst und &uuml;berarbeitet<\/li>\n<li>Erweiterung des Datenschutzhinweises (Tooltip oder Link zur Datenschutzseite)<\/li>\n<li>Nicht genutzte \/ nicht mehr zeitgem&auml;&szlig;e Funktionen entfernt<\/li>\n<\/ul>\n\n<p>Version 4.1:<\/p>\n\n<ul>\n<li>flodjiShare ist auch Wordpress 4.3 kompatibel<\/li>\n<\/ul>\n\n<p>Version 4.0:<\/p>\n\n<ul>\n<li>Code optimiert: CSS Anweisungen f&uuml;r die mobile Share Bar angepasst, so dass keine Rahmen mehr um die Share Buttons erscheinen k&ouml;nnen.<\/li>\n<\/ul>\n\n<p>Version 3.9.9:<\/p>\n\n<ul>\n<li>Code optimiert: CSS Anweisungen angepasst, so dass keine Rahmen mehr um die Buttons im Flatmix entstehen k&ouml;nnen.<\/li>\n<li>Neue Option: Gr&ouml;&szlig;e der Counterbox im Flatmix Design kann nun ge&auml;ndert werden.<\/li>\n<li>Backend: Links im Backend aufger&auml;umt.<\/li>\n<li>Bilder: found-footage.de Logo aktualisiert.<\/li>\n<li>Neue Funktion: Der Speichern Button in den flodjiShare Einstellungen befindet sich nun sowohl &uuml;ber als auch unter den Einstellungen.<\/li>\n<\/ul>\n\n<p>Version 3.9.8:<\/p>\n\n<ul>\n<li>Code optimiert: Bessere Kompatibilit&auml;t zu Wordpress Installationen in Unterordnern.<\/li>\n<li>Neue Funktion: Seitenaufrufe werden auf Wunsch nun auch in der Beitrags- \/ Seiten&uuml;bersicht angezeigt.<\/li>\n<li>Code optimiert: Inline CSS Strukturen in css Datei ausgelagert.<\/li>\n<\/ul>\n\n<p>Version 3.9.7:<\/p>\n\n<ul>\n<li>Code optimiert: site_url anstatt home_url verwendet um Fehler bei WP Installationen in Unterordnern zu vermeiden.<\/li>\n<li>Neue Funktion: Beitrags Statistiken unter den Share Buttons. Hier werden alle Shares zusammengerechnet und die Anzahl der Seitenaufrufe angezeigt.<\/li>\n<\/ul>\n\n<p>Version 3.9.6:<\/p>\n\n<ul>\n<li>Fehler behoben: Problem mit Sonderzeichen beim Teilen &uuml;ber Whatsapp behoben.<\/li>\n<\/ul>\n\n<p>Version 3.9.5:<\/p>\n\n<ul>\n<li>Fehler behoben: Bei aktiviertem Wordpress SEO Plugin wurde die falsche Description in die Metatags eingef&uuml;gt.<\/li>\n<\/ul>\n\n<p>Version 3.9.4:<\/p>\n\n<ul>\n<li>Fehler behoben: flattr und Digg Button fehlten im Flatmix Design<\/li>\n<li>Fehler behoben: Bei manchen Themes trat im Flatmix Design ein unsch&ouml;ner Abstand zwischen Logo und Counter auf<\/li>\n<li>Fehler behoben: Buttons im Flatmix Design konnten nicht zentriert werden<\/li>\n<\/ul>\n\n<p>Version 3.9.3:<\/p>\n\n<ul>\n<li>Fehler behoben: Problem mit Umlauten im Klickz&auml;hler behoben. Umlaute werden nun f&uuml;r den Z&auml;hlvorgang umgewandelt.<\/li>\n<li>Fehler behoben: Problem f&uuml;r Fehlermeldung: Warning: stripslashes() expects parameter 1 to be string, array given .... behoben.<\/li>\n<li>Code Optimierungen: Jeder Share Button wird jetzt &uuml;ber eine eigene Funktion aufgerufen.<\/li>\n<li>Button Mix: Bei aktiviertem Flat Design kann nun ein Mix aus Bild und CSS Button aktiviert werden (nur bei aktiviertem Counter)<\/li>\n<\/ul>\n\n<p>Version 3.9.2:<\/p>\n\n<ul>\n<li>Neue Funktion: Die &Uuml;berschrift der Share Buttons (z.B. Diesen Beitrag teilen) kann nun in der Gr&ouml;&szlig;e angepasst werden.<\/li>\n<li>Neue Funktion: Found-Footage.de Feed Widget eingebaut.<\/li>\n<li>Neue Funktion: Datenbank Pr&auml;fix kann nun ge&auml;ndert werden.<\/li>\n<\/ul>\n\n<p>Version 3.9.1:<\/p>\n\n<ul>\n<li>Bugfix: Problem mit Klickz&auml;hler und Umlauten behoben.<\/li>\n<\/ul>\n\n<p>Version 3.9:<\/p>\n\n<ul>\n<li>Bugfix: CSS Klassen wurden nicht geladen, wenn der Klickz&auml;hler deaktiviert war.<\/li>\n<\/ul>\n\n<p>Version 3.8.1:<\/p>\n\n<ul>\n<li>Fehler behoben: CSS Fehler beim Flat Design behoben<\/li>\n<\/ul>\n\n<p>Version 3.8:<\/p>\n\n<ul>\n<li>Neues Design: Flat Design<\/li>\n<li>Neue Funktion: Gro&szlig;e Buttons aktivieren (Button Design)<\/li>\n<li>Neue Funktion: Buttons zentrieren (Alle Designs)<\/li>\n<\/ul>\n\n<p>Version 3.7:<\/p>\n\n<ul>\n<li>Klick Counter: Problem mit Umlauten im Title behoben.<\/li>\n<\/ul>\n\n<p>Version 3.6:<\/p>\n\n<ul>\n<li>Klick Counter: Weitere Filter f&uuml;r den Klickz&auml;hler.<\/li>\n<\/ul>\n\n<p>Version 3.5:<\/p>\n\n<ul>\n<li>Klick Counter: Es kann nun nach einzelnen Netzwerken gefiltert werden.<\/li>\n<li>Neue Buttons: Add to Feedly + Pocket Buttons hinzugef&uuml;gt.<\/li>\n<li>Fehlender Button: Amazon Button (Plugin Einstellungen) fehlte.<\/li>\n<li>Whatsapp Share Button: Der Button ist jetzt auch f&uuml;r Android User mit aktueller Whatsapp Version nutzbar.<\/li>\n<\/ul>\n\n<p>Version 3.4:<\/p>\n\n<ul>\n<li>Code aufger&auml;mt: Veraltete PHP Funktionen ersetzt.<\/li>\n<li>Einstellungen angepasst: Rechte Spalte erneuert und Klickz&auml;hler &uuml;berarbeitet.<\/li>\n<li>Buttons: GIF Buttons in PNG Dateien umgewandelt und komprimiert<\/li>\n<\/ul>\n\n<p>Version 3.3:<\/p>\n\n<ul>\n<li>Neue Funktion: Sharebar f&uuml;r Android und iOS Ger&auml;te<\/li>\n<\/ul>\n\n<p>Version 3.2:<\/p>\n\n<ul>\n<li>Neuer Button: Whatsapp Share Button hinzugef&uuml;gt (Aktuell nur f&uuml;r iOS Ger&auml;te).<\/li>\n<\/ul>\n\n<p>Version 3.1:<\/p>\n\n<ul>\n<li>Korrektur: Feed Adresse in den Einstellungen korrigiert.<\/li>\n<\/ul>\n\n<p>Version 3.0:<\/p>\n\n<ul>\n<li>Neue Funktion: Bis zu drei eigene Share Buttons definierbar.<\/li>\n<li>Neue Funktion: Google News Keywords Tag<\/li>\n<li>Neue Funktion: Keywords Metatag<\/li>\n<\/ul>\n\n<p>Version 2.9:<\/p>\n\n<ul>\n<li>Bugfix: Kleinen CSS Fehler behoben.<\/li>\n<li>Neue Funktion: flodjiShare kann jetzt durch Sprachdateien &uuml;bersetzt werden.<\/li>\n<\/ul>\n\n<p>Version 2.8:<\/p>\n\n<ul>\n<li>Code Update: Kleine Sch&ouml;hnheits OP an den Plugin Einstellungen<\/li>\n<\/ul>\n\n<p>Version 2.7:<\/p>\n\n<ul>\n<li>Code Update: Kleinere Korekturen<\/li>\n<li>Neue Funktion: flodjiShare in Kategorie-Ansicht, Archiven und Suchergebnissen aktivieren \/ deaktivieren<\/li>\n<li>Neue Funktion: Meta Description Tag ein- \/ausblenden<\/li>\n<\/ul>\n\n<p>Version 2.6:<\/p>\n\n<ul>\n<li>Neuer Button: Flattr Button hinzugef&uuml;gt.<\/li>\n<li>Fehler behoben: Der Support Link \/ Datenschutz Hinweis wurde teilweise neben den Share Buttons angezeigt.<\/li>\n<\/ul>\n\n<p>Version 2.5:<\/p>\n\n<ul>\n<li>Neue Funktion: Metabox unter Beitr&auml;gen, Seiten und Custom Post Types f&uuml;r individuelle Snippet Gestaltung.<\/li>\n<li>Neue Funktion: Einzelne Beitr&auml;ge\/Seiten\/Custom Post Types per ID ausschlie&szlig;en.<\/li>\n<\/ul>\n\n<p>Version 2.4:<\/p>\n\n<ul>\n<li>Code Update: Klickz&auml;hler z&auml;hlt nun keine Bots mehr.<\/li>\n<li>Code Update: Bl&auml;tterfunktion f&uuml;r Klickz&auml;hler optimiert.<\/li>\n<\/ul>\n\n<p>Version 2.3:<\/p>\n\n<ul>\n<li>Neue Anzeigeposition: &Uuml;ber und Unter Beitr&auml;ge gleichzeitig.<\/li>\n<li>Google Plus Authorship Markup<\/li>\n<li>Share Buttons f&uuml;r einzelne Custom-Post-Types aktivieren bzw. deaktivieren<\/li>\n<li>Multi-Autor Unterst&uuml;tzung f&uuml;r Google Authorship Markup und Twitter Cards.<\/li>\n<\/ul>\n\n<p>Version 2.2:<\/p>\n\n<ul>\n<li>Fehler behoben: Share Buttons wurden auch im Feed angezeigt.<\/li>\n<\/ul>\n\n<p>Version 2.1:<\/p>\n\n<ul>\n<li>Neue Funktion: Klickz&auml;hler f&uuml;r die Share-Buttons im Metro Design (Kann nach Bedarf aktiviert bzw. deaktiviert werden).<\/li>\n<li>Code Update: Opengraph Schema wird nur noch bei aktiviertem Opengraph Support angezeigt.<\/li>\n<li>Neue Funktion: flodjiShare Einstellungen haben jetzt eigene Men&uuml;punkte im WordPress Admin-Bereich.<\/li>\n<li>Neue Funktion: Neuer Punkt \"flodjiShare Klick Counter\" im flodjiShare Men&uuml;. Zeigt die Anzahl der Klicks auf die Buttons pro Button bzw. pro Beitrag an.<\/li>\n<li>Code Update: CSS-Anweisungen erfolgen jetzt aus eigener CSS-Datei.<\/li>\n<\/ul>\n\n<p>Version 2.0:<\/p>\n\n<ul>\n<li>Code Update: Neues Meta Tag f&uuml;r Rich Snippets: Interaction Count. In diesem Meta Tag wird die Anzahl der Kommentare f&uuml;r einen Artikel angezeigt.<\/li>\n<li>Code Update: Schema aus HTML Tag entfernt und in Meta Tag Bereich eingef&uuml;gt.<\/li>\n<\/ul>\n\n<p>Version 1.9:<\/p>\n\n<ul>\n<li>Einstellungen &uuml;berarbeitet:\n\n<ul>\n<li>flodji.de Feed und Links hinzugef&uuml;gt<\/li>\n<\/ul><\/li>\n<li>Datenschutzhinweis-Option eingebaut<\/li>\n<li>Deaktivierbaren Supportlink eingebaut<\/li>\n<\/ul>\n\n<p>Version 1.8:<\/p>\n\n<ul>\n<li>Text &uuml;ber den Buttons ist nun editierbar.<\/li>\n<li>Facebook Link in den Plugin Einstellungen korrigiert.<\/li>\n<\/ul>\n\n<p>Version 1.7:<\/p>\n\n<ul>\n<li>Buttons k&ouml;nnen nun auch ganz einfach per Shortcode [flodjishare] eingebunden werden.<\/li>\n<\/ul>\n\n<p>Version 1.6:<\/p>\n\n<ul>\n<li>Metro Design lies sich nicht mehr deaktivieren.<\/li>\n<\/ul>\n\n<p>Version 1.5:<\/p>\n\n<ul>\n<li>Zus&auml;tzliches Design (metro) ausw&auml;hlbar<\/li>\n<li>Kleinere Bugfixes im Code (z.B. Fehler bei fehlendem Excerpt)<\/li>\n<\/ul>\n\n<p>Version 1.4:<\/p>\n\n<ul>\n<li>Neue Share Buttons: LinkedIn, Pinterest, Stumbleupon, Tumblr<\/li>\n<li>Neues Buttonset<\/li>\n<\/ul>","raw_excerpt":"Just install flodjiShare to enable Social Sharing on your Wordpress site.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/21145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=21145"}],"author":[{"embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/flodji"}],"wp:attachment":[{"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=21145"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=21145"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=21145"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=21145"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=21145"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/lmo.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=21145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}